{"id":2955,"date":"2018-09-10T15:30:48","date_gmt":"2018-09-10T13:30:48","guid":{"rendered":"https:\/\/fuel-it.io\/?p=2955"},"modified":"2026-01-26T10:34:13","modified_gmt":"2026-01-26T09:34:13","slug":"fuel-it-present-au-salon-mif-expo","status":"publish","type":"post","link":"https:\/\/fuel-it.io\/fr\/fuel-it-present-au-salon-mif-expo\/","title":{"rendered":"Fuel it pr\u00e9sent au salon MIF Expo"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1100px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2>MIFEXPO : le salon du made in France<\/h2>\n<p><a href=\"http:\/\/www.mifexpo.fr\/\">Le Made In France<\/a> sera \u00e0 l\u2019honneur \u00e0 la Porte de Versailles \u00e0 Paris. Rendez-vous donc au salon MIF Expo !<\/p>\n<p>Il rassemblera notamment plus de 60 000 personnes autour de <strong>450<\/strong> exposants.<\/p>\n<p>Ainsi, acteur incontournable dans l\u2019\u00e9volution du made in France, MIF Expo propose avec son salon, une vitrine de l\u2019industrie, de l\u2019innovation et de la cr\u00e9ativit\u00e9 fran\u00e7aise. Leur objectif :\u00a0 les faire rencontrer les consommateurs.<\/p>\n<p>MIF Expo refl\u00e8te donc et tente d\u2019amplifier une dynamique socio-\u00e9conomique. Celle d\u2019entreprises qui ont fait le choix de r\u00e9aliser sur notre territoire les \u00e9tapes essentielles de la fabrication de leurs produits.<\/p>\n<h3>Fuel it pr\u00e9sent, rendez-vous stand F83<\/h3>\n<p>Nous exposeront nos produits \u00e0 cet \u00e9v\u00e9nement qui se d\u00e9roulera \u00e0 Paris en novembre !<\/p>\n<p>Int\u00e9gralement, con\u00e7u, d\u00e9velopp\u00e9 et assembl\u00e9 en Bourgogne Franche Comt\u00e9, le capteur Fuel it y aura bien entendu sa place (et en plein c\u0153ur du Pavillon Innovation!).<\/p>\n<p>C&rsquo;est pourquoi, l\u2019ensemble de nos produits sera directement propos\u00e9 \u00e0 la vente.<\/p>\n<p>Nous serons \u00e9galement disponibles pour r\u00e9pondre \u00e0 vos questions, vous pr\u00e9senter notre nouveau d\u00e9monstrateur, nos applications web et bien d\u2019autres choses encore.<\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 en parler autour de vous, nous vous attendons nombreux.<\/p>\n<p>Rendez-vous sur notre stand <strong>stand emplacement F83<\/strong>\u00a0(ou sur notre <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/fuel-it.io\/\">site internet<\/a><\/em><\/span>!).<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[303],"tags":[],"class_list":["post-2955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-fuel-it"],"_links":{"self":[{"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/posts\/2955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/comments?post=2955"}],"version-history":[{"count":4,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/posts\/2955\/revisions"}],"predecessor-version":[{"id":10651,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/posts\/2955\/revisions\/10651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/media\/3168"}],"wp:attachment":[{"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/media?parent=2955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/categories?post=2955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuel-it.io\/fr\/wp-json\/wp\/v2\/tags?post=2955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}